{"id":56577,"date":"2024-10-03T08:36:52","date_gmt":"2024-10-03T06:36:52","guid":{"rendered":"https:\/\/vsa-aas.ch\/job\/wissenschaftlichen-mitarbeiterin-80-5\/"},"modified":"2024-11-02T00:56:03","modified_gmt":"2024-11-01T23:56:03","slug":"wissenschaftlichen-mitarbeiterin-80-5","status":"expired","type":"job_listing","link":"https:\/\/vsa-aas.ch\/it\/?post_type=job_listing&p=56577","title":{"rendered":"Wissenschaftliche:n Mitarbeiter:in (80%)"},"content":{"rendered":"<p>Das Staatsarchiv des Kantons Z\u00fcrich sucht per 1. Mai 2025 oder nach Vereinbarung eine:n<\/p>\n<p><strong>Wissenschaftliche:n Mitarbeiter:in (80%)<\/strong><\/p>\n<p>Weitere Informationen entnehmen Sie bitte dem <a href=\"https:\/\/vsa-aas.ch\/wp-content\/uploads\/2024\/10\/Inserat-wMA-AEIKD-per-01.05.2025-externes-Inserat.pdf\" target=\"_blank\" rel=\"noopener\">PDF<\/a>.<\/p>\n","protected":false},"author":9,"featured_media":29349,"template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_promoted":"","_job_location":"Z\u00fcrich","_application":"","_company_name":"Staatsarchiv des Kantons Z\u00fcrich","_company_website":"","_company_tagline":"","_company_twitter":"","_company_video":"","_filled":0,"_featured":0,"_remote_position":0,"_job_salary":"","_job_salary_currency":"","_job_salary_unit":""},"job-types":[],"class_list":["post-56577","job_listing","type-job_listing","status-expired","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/vsa-aas.ch\/it\/wp-json\/wp\/v2\/job-listings\/56577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vsa-aas.ch\/it\/wp-json\/wp\/v2\/job-listings"}],"about":[{"href":"https:\/\/vsa-aas.ch\/it\/wp-json\/wp\/v2\/types\/job_listing"}],"author":[{"embeddable":true,"href":"https:\/\/vsa-aas.ch\/it\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":3,"href":"https:\/\/vsa-aas.ch\/it\/wp-json\/wp\/v2\/job-listings\/56577\/revisions"}],"predecessor-version":[{"id":56589,"href":"https:\/\/vsa-aas.ch\/it\/wp-json\/wp\/v2\/job-listings\/56577\/revisions\/56589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vsa-aas.ch\/it\/wp-json\/wp\/v2\/media\/29349"}],"wp:attachment":[{"href":"https:\/\/vsa-aas.ch\/it\/wp-json\/wp\/v2\/media?parent=56577"}],"wp:term":[{"taxonomy":"job_listing_type","embeddable":true,"href":"https:\/\/vsa-aas.ch\/it\/wp-json\/wp\/v2\/job-types?post=56577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}